{"id":2351,"date":"2024-12-31T15:11:28","date_gmt":"2024-12-31T14:11:28","guid":{"rendered":"https:\/\/closdessentinelles.com\/?p=2351"},"modified":"2024-12-31T15:11:28","modified_gmt":"2024-12-31T14:11:28","slug":"hydromels-historiques-image-innee-immuable-2009","status":"publish","type":"post","link":"https:\/\/closdessentinelles.com\/index.php\/2024\/12\/31\/hydromels-historiques-image-innee-immuable-2009\/","title":{"rendered":"Hydromels Historiques : Image Inn\u00e9e &#038; Immuable (2009)"},"content":{"rendered":"<div class=\"prose dark:prose-invert inline leading-normal break-words min-w-0 [word-break:break-word]\">\n<h2 class=\"mb-2 mt-6 text-lg first:mt-3\">Les Hydromels Historiques du Clos des Sentinelles : Image Inn\u00e9e et Immuable<\/h2>\n<p><strong>Une Tradition N\u00e9e en 2009<\/strong> Depuis 2009, le Clos des Sentinelles a r\u00e9volutionn\u00e9 le monde de l&#8217;hydromel avec deux cuv\u00e9es embl\u00e9matiques : <strong>Image Inn\u00e9e<\/strong> et <strong>Immuable<\/strong>. Ces deux hydromels repr\u00e9sentent l&#8217;essence m\u00eame de notre savoir-faire artisanal et notre approche innovante de la vinification du miel.<\/p>\n<h2 class=\"mb-2 mt-6 text-lg first:mt-3\">Une M\u00e9thode d&#8217;Assemblage Unique<\/h2>\n<p>La particularit\u00e9 de ces deux hydromels r\u00e9side dans leur <strong>processus d&#8217;\u00e9laboration novateur<\/strong> : chaque miel est vinifi\u00e9 s\u00e9par\u00e9ment avant d&#8217;\u00eatre soigneusement assembl\u00e9. Cette technique permet de pr\u00e9server les caract\u00e9ristiques uniques de chaque terroir et de cr\u00e9er des hydromels complexes et harmonieux. m\u00eame le choix du degr\u00e9 alcoolique joue un choix crucial pour fix\u00e9 en \u00e9quilibre les mol\u00e9cules aromatiques.<\/p>\n<h2 class=\"mb-2 mt-6 text-lg first:mt-3\">Image Inn\u00e9e : Imaginez-vous l&#8217;harmonie parfaite entre Miel et di-Vin<\/h2>\n<p class=\"mb-2 mt-6 text-lg first:mt-3\">La Premi\u00e8re Cuv\u00e9e : <strong>Image Inn\u00e9e<\/strong>, n\u00e9e en 2009, est notre premi\u00e8re cuv\u00e9e. M\u00e9daill\u00e9e d&#8217;Or au Concours R\u00e9gional des Miels \u00ab Sud de France \u00bb 2010\/2011 et au Concours G\u00e9n\u00e9ral Agricole de Paris 2013, elle a rapidement conquis les amateurs d&#8217;hydromel. C&#8217;est un assemblage de miels vinifi\u00e9s s\u00e9par\u00e9ment ce qui lui apporte un grande complexit\u00e9 aromatique. une tr\u00e8s bonne approche pour les n\u00e9ophyte de l&#8217;hydromel. L\u00e9ger et faiblement sucr\u00e9 il accompagnera parfaitement un bon foie gras mi-cuit avec un pain d&#8217;\u00e9pice l\u00e9g\u00e8rement grill\u00e9.<\/p>\n<h2 class=\"mb-2 mt-6 text-lg first:mt-3\">Immuable : L&#8217;hydromel qui traverse les \u00e2ges<\/h2>\n<p class=\"mb-2 mt-6 text-lg first:mt-3\">La Cuv\u00e9e Historique : <strong>Immuable<\/strong>, \u00e9galement cr\u00e9\u00e9e en 2009, compl\u00e8te notre gamme avec une personnalit\u00e9 tout aussi distinctive. Ces deux hydromels ont pos\u00e9 les fondations de notre r\u00e9putation dans le monde des boissons artisanales. Cr\u00e9\u00e9e simultan\u00e9ment \u00e0 Image Inn\u00e9e en 2009, comme image inn\u00e9e, c&#8217;est un assemblage de miels vinifi\u00e9s s\u00e9par\u00e9ment<\/p>\n<h2 class=\"mb-2 mt-6 text-lg first:mt-3\">Une Tradition en \u00c9volution<\/h2>\n<p>Contrairement \u00e0 notre nouvelle cuv\u00e9e <strong>Impertinant<\/strong> lanc\u00e9e en janvier, Image Inn\u00e9e et Immuable repr\u00e9sentent nos racines, notre histoire depuis plus de 15 ans. Elles continuent de s\u00e9duire les amateurs d&#8217;hydromels par leur caract\u00e8re unique et leur qualit\u00e9 constante.<\/p>\n<\/div>\n<div><\/div>\n<div class=\"prose dark:prose-invert inline leading-normal break-words min-w-0 [word-break:break-word]\">\n<p><strong>Suggestions de D\u00e9gustation<\/strong><\/p>\n<ul class=\"marker:text-textOff list-disc pl-8\">\n<li>Servir frais, entre 6 et 8\u00b0C<\/li>\n<li>Parfait en ap\u00e9ritif<\/li>\n<li>Accompagne id\u00e9alement les pr\u00e9parations au foie gras<\/li>\n<li>Se marie merveilleusement avec des desserts<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les Hydromels Historiques du Clos des Sentinelles : Image Inn\u00e9e et Immuable Une Tradition N\u00e9e en 2009 Depuis 2009, le Clos des Sentinelles a r\u00e9volutionn\u00e9 le monde de l&#8217;hydromel avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[61,60,3],"tags":[],"class_list":["post-2351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-clos-des-sentinelles","category-hydromels"],"_links":{"self":[{"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/posts\/2351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/comments?post=2351"}],"version-history":[{"count":2,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/posts\/2351\/revisions"}],"predecessor-version":[{"id":2353,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/posts\/2351\/revisions\/2353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/media\/2347"}],"wp:attachment":[{"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/media?parent=2351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/categories?post=2351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/closdessentinelles.com\/index.php\/wp-json\/wp\/v2\/tags?post=2351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}